{"id":35097,"date":"2016-08-25T14:13:32","date_gmt":"2016-08-25T12:13:32","guid":{"rendered":"https:\/\/www.pk.hr\/palfinger-epsilon-c70z73-crane-and-m16t-container-loader-for-man-importer-hrvatska-kemis-termoclean-d-o-o\/"},"modified":"2025-05-04T19:14:29","modified_gmt":"2025-05-04T17:14:29","slug":"palfinger-epsilon-c70z73-crane-and-m16t-container-loader-for-man-importer-hrvatska-kemis-termoclean-d-o-o","status":"publish","type":"post","link":"https:\/\/www.pk.hr\/en\/palfinger-epsilon-c70z73-crane-and-m16t-container-loader-for-man-importer-hrvatska-kemis-termoclean-d-o-o\/","title":{"rendered":"Palfinger Epsilon C70Z73 Crane and M16T Container Loader for Man Importer Hrvatska \u2013 Kemis Termoclean d.o.o."},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<p class=\"\" data-start=\"212\" data-end=\"462\">A specialized municipal vehicle upgrade has been delivered to Kemis Termoclean d.o.o. through Man Importer Hrvatska, featuring a Palfinger M16T <a href=\"https:\/\/www.palfinger.com\/en\/products\/hookloader-skiploader\/models?categoryIds0%5B%5D=119\" target=\"_blank\" rel=\"noopener\">container loader<\/a> and a Palfinger Epsilon<a href=\"https:\/\/www.palfingerepsilon.com\/en\/Recycling\/Scrap-manipulation\/C-Serie-Epsolution?type=Z-Kran\" target=\"_blank\" rel=\"noopener\"> C70Z73<\/a> crane equipped with an FG31R waste grapple.<\/p>\n<p class=\"\" data-start=\"464\" data-end=\"726\">The system is additionally fitted with Scanreco (RCE) remote control and AS180 hydraulic stabilizers with a 180\u00b0 swing capability, ensuring optimal safety and flexibility when operating in demanding waste handling environments.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"cq-dagallery-container\" style=\"width:80%;margin:0 auto;\"><ul class=\"cq-dagallery\" data-gallerywidth=\"80%\" data-width=\"auto\" data-height=\"auto\" data-color=\"#ffffff\" data-background=\"#dd3333\" data-opacity=\"0.8\"><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_2.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_2.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_3.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_3.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_4.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_4.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_5.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_5.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_6.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_6.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_7.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_7.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_8.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_8.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_9.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_9.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_10.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_10.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><li class=\"\" data-width=\"auto\" data-height=\"auto\" data-margin=\"5px\" style=\"margin:5px\"><a class=\"normal\" href=\"https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_11.jpg\" rel=\"3509789\"><img src='https:\/\/www.pk.hr\/wordpress\/wp-content\/uploads\/2022\/06\/Palfinger_Epsilon_dizalica_C70Z73_i_samopodizac_kontenjera_M_16_T_11.jpg' width='auto' height='auto' alt='Palfinger_Epsilon_dizalica_C70Z73_i_samopodiza\u010d_kontenjera_M_16_T' \/><\/a><div class=\"dagallery-info\" style=\"padding:20px;color:#ffffff;background-color:#dd3333\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;] A specialized municipal vehicle upgrade has been delivered to Kemis Termoclean d.o.o. through Man Importer Hrvatska, featuring a Palfinger M16T container loader and a Palfinger Epsilon C70Z73 crane equipped with an FG31R waste grapple. The system is additionally fitted with Scanreco (RCE) remote control and AS180 hydraulic stabilizers with a 180\u00b0 swing capability, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":25068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[520],"tags":[604,536,530,835,714],"class_list":["post-35097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deliveries","tag-communal-services","tag-cranes","tag-palfinger-en","tag-recycling-en-2","tag-samopodizac-kontejnera-en"],"_links":{"self":[{"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/posts\/35097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/comments?post=35097"}],"version-history":[{"count":6,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/posts\/35097\/revisions"}],"predecessor-version":[{"id":35103,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/posts\/35097\/revisions\/35103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/media\/25068"}],"wp:attachment":[{"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/media?parent=35097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/categories?post=35097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pk.hr\/en\/wp-json\/wp\/v2\/tags?post=35097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}